{"id":25817,"date":"2013-04-12T08:11:26","date_gmt":"2013-04-12T06:11:26","guid":{"rendered":"https:\/\/www.arrediliturgici.it\/prodotto\/handchise-silver-ring-art-31\/"},"modified":"2022-05-20T12:40:48","modified_gmt":"2022-05-20T10:40:48","slug":"anello-alfa-omega-in-argento","status":"publish","type":"product","link":"https:\/\/www.arrediliturgici.it\/en\/prodotto\/anello-alfa-omega-in-argento\/","title":{"rendered":"Anello \u201calfa-omega\u201d in argento"},"content":{"rendered":"<h2><strong>Anello \u201cAlfa-Omega\u201d in argento (art.31)<\/strong><\/h2>\n<p><strong>L&#8217;anello \u201cAlfa-Omega\u201d in argento <\/strong>\u00e8 un prezioso articolo vescovile realizzato in <strong>argento bicolore.<\/strong><\/p>\n<p>L\u2019<strong>anello vescovile<\/strong> \u00e8, insieme al pastorale, alla mitria e alla croce pettorale, una delle <strong>insegne episcopali<\/strong> consegnate al vescovo durante la celebrazione di <strong>ordinazione episcopale<\/strong>. Esso pu\u00f2 essere d\u2019<strong>argento<\/strong> o di <strong>oro<\/strong> e rappresenta la fedelt\u00e0 del vescovo alla<strong> Chiesa di Cristo<\/strong>.<\/p>\n<p>Questo anello \u00e8 un prezioso oggetto di oreficeria sacra realizzato in argento e decorato con una raffinata cesellatura realizzata a mano che rappresenta i simboli cristiani dell&#8217;<strong>Alfa e Omega<\/strong> e il monogramma di Cristo &#8220;<strong>Chi-Rho<\/strong>&#8220;<strong>.<\/strong><\/p>\n<p><strong>Chiseling is<\/strong> a processing that is generally carried out on precious metals; it consists in the cold plastic deformation of the metal performed with the chisel. It produces a relief workmanship, made with engravings and changes.<\/p>\n<p>Questa <strong> insegna episcopale <\/strong>\u00e8 un oggetto personalizzato di <strong>high liturgical craftsmanship<\/strong> handmade in Italy for the <strong>store<\/strong> of sacred furnishings <strong>Maranatha, <\/strong>Italian laboratory of <strong>sacred vestments<\/strong> and <strong>arredi liturgici<\/strong> in cui originalit\u00e0, qualit\u00e0 delle materie prime ed eccellenza artigianale danno vita ad <strong>articoli religiosi<\/strong> e <strong>confezioni sartoriali<\/strong> fatti a mano di altissima qualit\u00e0.<\/p>\n<p>Maranatha Lab is a liturgical laboratory<strong> Lucanian,<\/strong> the result of a combination of traditional heritage of craft techniques and design innovation, as well as a place of synergies and artistic and creative collaborations<strong> .<\/strong><\/p>\n<p>Maranatha Lab&#8217;s episcopal articles all have the singularity of being identified with <strong>custom names.<\/strong> <strong> <\/strong><\/p>\n<p>This is an <strong>artisan product<\/strong> of quality and quality made <strong>in Italy.<\/strong><\/p>\n<h4><strong>Standard size<\/strong><\/h4>\n<h3><strong>Details:<\/strong><\/h3>\n<ul>\n<li>two-tone silver<\/li>\n<li>modern style<\/li>\n<li>chiseled by hand<\/li>\n<li>made in Italy<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><strong>Anello \u201cAlfa-Omega\u201d in argento <\/strong>bicolore cesellato a mano con i simboli cristiani del &#8220;Chi-Rho&#8221; e dell&#8221;Alfa e Omega&#8221;. <strong>Manufatto di pregio e qualit\u00e0 made in Italy <\/strong> <\/p>\n","protected":false},"featured_media":25827,"template":"","meta":[],"product_cat":[735,882],"product_tag":[3650,4093,5318,5340,11046,11286,11287,11288,11289,2694,11305,2703,11306,2706,2708,2803,2804,3517],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arredi Sacri Anello \u201cAlfa-Omega\u201d in argento | Maranath\u00e0 - Liturgucal furnishings<\/title>\n<meta name=\"description\" content=\"Anello \u201cAlfa-Omega\u201d in argento bicolore cesellato a mano con i simboli cristiani del &quot;Chi-Rho&quot; e dell&quot;Alfa e Omega&quot;. Manufatto di pregio e qualit\u00e0 made in Italy\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.arrediliturgici.it\/en\/prodotto\/anello-alfa-omega-in-argento\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arredi Sacri Anello \u201cAlfa-Omega\u201d in argento | Maranath\u00e0 - Liturgucal furnishings\" \/>\n<meta property=\"og:description\" content=\"Anello \u201cAlfa-Omega\u201d in argento bicolore cesellato a mano con i simboli cristiani del &quot;Chi-Rho&quot; e dell&quot;Alfa e Omega&quot;. Manufatto di pregio e qualit\u00e0 made in Italy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.arrediliturgici.it\/en\/prodotto\/anello-alfa-omega-in-argento\/\" \/>\n<meta property=\"og:site_name\" content=\"Maranath\u00e0 - Liturgucal furnishings\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/arredisacri\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-20T10:40:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.arrediliturgici.it\/content\/wp-content\/uploads\/2019\/11\/anello-in-argento-cesellato-a-mano-art-31.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"228\" \/>\n\t<meta property=\"og:image:height\" content=\"247\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.arrediliturgici.it\/en\/prodotto\/anello-alfa-omega-in-argento\/\",\"url\":\"https:\/\/www.arrediliturgici.it\/en\/prodotto\/anello-alfa-omega-in-argento\/\",\"name\":\"Arredi Sacri Anello \u201cAlfa-Omega\u201d in argento | Maranath\u00e0 - Liturgucal furnishings\",\"isPartOf\":{\"@id\":\"https:\/\/www.arrediliturgici.it\/en\/#website\"},\"datePublished\":\"2013-04-12T06:11:26+00:00\",\"dateModified\":\"2022-05-20T10:40:48+00:00\",\"description\":\"Anello \u201cAlfa-Omega\u201d in argento bicolore cesellato a mano con i simboli cristiani del \\\"Chi-Rho\\\" e dell\\\"Alfa e Omega\\\". Manufatto di pregio e qualit\u00e0 made in Italy\",\"breadcrumb\":{\"@id\":\"https:\/\/www.arrediliturgici.it\/en\/prodotto\/anello-alfa-omega-in-argento\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.arrediliturgici.it\/en\/prodotto\/anello-alfa-omega-in-argento\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.arrediliturgici.it\/en\/prodotto\/anello-alfa-omega-in-argento\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.arrediliturgici.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All categories of liturgical furnishings\",\"item\":\"https:\/\/www.arrediliturgici.it\/en\/all-categories-of-liturgical-furniture\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Anello \u201calfa-omega\u201d in argento\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.arrediliturgici.it\/en\/#website\",\"url\":\"https:\/\/www.arrediliturgici.it\/en\/\",\"name\":\"Maranath\u00e0 - Liturgucal furnishings\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.arrediliturgici.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.arrediliturgici.it\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.arrediliturgici.it\/en\/#organization\",\"name\":\"Maranath\u00e0 - Liturgucal furnishings\",\"url\":\"https:\/\/www.arrediliturgici.it\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.arrediliturgici.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.arrediliturgici.it\/content\/wp-content\/uploads\/2019\/09\/logo-maranatha-arredi-liturgici-250x91.png\",\"contentUrl\":\"https:\/\/www.arrediliturgici.it\/content\/wp-content\/uploads\/2019\/09\/logo-maranatha-arredi-liturgici-250x91.png\",\"width\":250,\"height\":91,\"caption\":\"Maranath\u00e0 - Liturgucal furnishings\"},\"image\":{\"@id\":\"https:\/\/www.arrediliturgici.it\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/arredisacri\/\"]}]}<\/script>\n<meta property=\"product:price:amount\" content=\"0.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"31\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arredi Sacri Anello \u201cAlfa-Omega\u201d in argento | Maranath\u00e0 - Liturgucal furnishings","description":"Anello \u201cAlfa-Omega\u201d in argento bicolore cesellato a mano con i simboli cristiani del \"Chi-Rho\" e dell\"Alfa e Omega\". Manufatto di pregio e qualit\u00e0 made in Italy","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.arrediliturgici.it\/en\/prodotto\/anello-alfa-omega-in-argento\/","og_locale":"en_US","og_type":"article","og_title":"Arredi Sacri Anello \u201cAlfa-Omega\u201d in argento | Maranath\u00e0 - Liturgucal furnishings","og_description":"Anello \u201cAlfa-Omega\u201d in argento bicolore cesellato a mano con i simboli cristiani del \"Chi-Rho\" e dell\"Alfa e Omega\". Manufatto di pregio e qualit\u00e0 made in Italy","og_url":"https:\/\/www.arrediliturgici.it\/en\/prodotto\/anello-alfa-omega-in-argento\/","og_site_name":"Maranath\u00e0 - Liturgucal furnishings","article_publisher":"https:\/\/www.facebook.com\/arredisacri\/","article_modified_time":"2022-05-20T10:40:48+00:00","og_image":[{"width":228,"height":247,"url":"https:\/\/www.arrediliturgici.it\/content\/wp-content\/uploads\/2019\/11\/anello-in-argento-cesellato-a-mano-art-31.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.arrediliturgici.it\/en\/prodotto\/anello-alfa-omega-in-argento\/","url":"https:\/\/www.arrediliturgici.it\/en\/prodotto\/anello-alfa-omega-in-argento\/","name":"Arredi Sacri Anello \u201cAlfa-Omega\u201d in argento | Maranath\u00e0 - Liturgucal furnishings","isPartOf":{"@id":"https:\/\/www.arrediliturgici.it\/en\/#website"},"datePublished":"2013-04-12T06:11:26+00:00","dateModified":"2022-05-20T10:40:48+00:00","description":"Anello \u201cAlfa-Omega\u201d in argento bicolore cesellato a mano con i simboli cristiani del \"Chi-Rho\" e dell\"Alfa e Omega\". Manufatto di pregio e qualit\u00e0 made in Italy","breadcrumb":{"@id":"https:\/\/www.arrediliturgici.it\/en\/prodotto\/anello-alfa-omega-in-argento\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.arrediliturgici.it\/en\/prodotto\/anello-alfa-omega-in-argento\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.arrediliturgici.it\/en\/prodotto\/anello-alfa-omega-in-argento\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.arrediliturgici.it\/en\/"},{"@type":"ListItem","position":2,"name":"All categories of liturgical furnishings","item":"https:\/\/www.arrediliturgici.it\/en\/all-categories-of-liturgical-furniture\/"},{"@type":"ListItem","position":3,"name":"Anello \u201calfa-omega\u201d in argento"}]},{"@type":"WebSite","@id":"https:\/\/www.arrediliturgici.it\/en\/#website","url":"https:\/\/www.arrediliturgici.it\/en\/","name":"Maranath\u00e0 - Liturgucal furnishings","description":"","publisher":{"@id":"https:\/\/www.arrediliturgici.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.arrediliturgici.it\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.arrediliturgici.it\/en\/#organization","name":"Maranath\u00e0 - Liturgucal furnishings","url":"https:\/\/www.arrediliturgici.it\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.arrediliturgici.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.arrediliturgici.it\/content\/wp-content\/uploads\/2019\/09\/logo-maranatha-arredi-liturgici-250x91.png","contentUrl":"https:\/\/www.arrediliturgici.it\/content\/wp-content\/uploads\/2019\/09\/logo-maranatha-arredi-liturgici-250x91.png","width":250,"height":91,"caption":"Maranath\u00e0 - Liturgucal furnishings"},"image":{"@id":"https:\/\/www.arrediliturgici.it\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/arredisacri\/"]}]},"product_price_amount":"0.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"31","product_condition":"new"},"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"_links":{"self":[{"href":"https:\/\/www.arrediliturgici.it\/en\/wp-json\/wp\/v2\/product\/25817"}],"collection":[{"href":"https:\/\/www.arrediliturgici.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.arrediliturgici.it\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.arrediliturgici.it\/en\/wp-json\/wp\/v2\/media\/25827"}],"wp:attachment":[{"href":"https:\/\/www.arrediliturgici.it\/en\/wp-json\/wp\/v2\/media?parent=25817"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.arrediliturgici.it\/en\/wp-json\/wp\/v2\/product_cat?post=25817"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.arrediliturgici.it\/en\/wp-json\/wp\/v2\/product_tag?post=25817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}